{"id":10268,"date":"2022-08-11T08:39:48","date_gmt":"2022-08-11T06:39:48","guid":{"rendered":"https:\/\/fruiturisme.info\/?p=10268"},"modified":"2022-08-11T11:23:08","modified_gmt":"2022-08-11T09:23:08","slug":"video-promotionnelle-du-fruit-aitona","status":"publish","type":"post","link":"https:\/\/fruiturisme.info\/fr\/video-promotionnelle-du-fruit-aitona\/","title":{"rendered":"Une vid\u00e9o pour faire un don \u00e0 Con\u00e8ixer et promouvoir le fruit d&#039;Aitona"},"content":{"rendered":"<h4 class=\"wp-block-heading\">Fruiturisme et la mairie d&#039;Aitona s&#039;engagent \u00e0 promouvoir et \u00e0 diffuser le fruit d&#039;Aitona, le plus joyeux du monde ! Enfin, cet \u00e9t\u00e9, nous avons pr\u00e9par\u00e9 une vid\u00e9o promotionnelle qui sera diffus\u00e9e sur TV3.<\/h4>\n\n\n\n<p class=\"has-white-color has-text-color\">.<\/p>\n\n\n\n<p>Depuis le d\u00e9but de la campagne estivale, la mairie d&#039;Aitona et Fruiturisme ont d\u00e9cid\u00e9 de continuer \u00e0 soutenir le processus de r\u00e9colte des fruits et leur s\u00e9lection de qualit\u00e9 locale. Aix\u00f2 com, dignify the pagesia tasca. Dans le cadre de la nouvelle campagne touristique \u201c Aitona, le go\u00fbt de l&#039;\u00e9t\u00e9 \u201d, <strong>Le consistori et Fruiturisme ont r\u00e9alis\u00e9 pour le premier exemplaire une vid\u00e9o promotionnelle mettant en sc\u00e8ne le fruit et son protagoniste principal.<\/strong>.<\/p>\n\n\n\n<p class=\"has-white-color has-text-color\" style=\"font-size:6px\">.<\/p>\n\n\n\n<p>Ce clip audiovisuel a \u00e9t\u00e9 publi\u00e9 par des m\u00e9dias comme TV3 et diffus\u00e9 sur les r\u00e9seaux sociaux de la mairie et du projet Fruiturisme. On y voit des images de la r\u00e9colte des fruits dans les champs. La vid\u00e9o est partag\u00e9e avec les<strong> collaboration des centres municipaux de fruits<\/strong>: Aitona Agricultura, Arfon Fruits, Espax, Frutaito, Fruitona et Produccions Agr\u00e0ries del Camp, \u00e0 qui la commune appr\u00e9cie et valorise son implication.<\/p>\n\n\n\n<p class=\"has-white-color has-text-color\" style=\"font-size:6px\">.<\/p>\n\n\n\n<p>Rosa Pujol, maire d&#039;Aitona, souligne qu&#039;il s&#039;agit d&#039;une initiative pionni\u00e8re et explique que <strong>\u201c Le fruit d&#039;Aitona n&#039;est pas seulement un gage de qualit\u00e9 unique \u00e0 notre r\u00e9gion, mais il repr\u00e9sente l&#039;essence m\u00eame d&#039;une page forte, dynamique et travailleuse. Autant de valeurs qui m\u00e9ritent d&#039;\u00eatre respect\u00e9es. \u201d<\/strong>.<\/p>\n\n\n\n<p class=\"has-white-color has-text-color\" style=\"font-size:6px\">.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" controls src=\"https:\/\/fruiturisme.info\/wp-content\/uploads\/CURT-1.mp4\"><\/video><\/figure>","protected":false},"excerpt":{"rendered":"<p>Fruiturisme et la Mairie d&#039;Aitona s&#039;engagent pour la promotion et la diffusion du fruit d&#039;Aitona, le plus joyeux du monde ! Cet \u00e9t\u00e9, nous avons r\u00e9alis\u00e9 une vid\u00e9o promotionnelle qui sera diffus\u00e9e sur TV3. Depuis le d\u00e9but de la campagne estivale, la Mairie d&#039;Aitona et Fruiturisme ont d\u00e9cid\u00e9 de poursuivre leur engagement \u00e0 soutenir le processus de collecte [\u2026]<\/p>","protected":false},"author":5,"featured_media":10269,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[165],"tags":[],"class_list":["post-10268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estiu"],"_links":{"self":[{"href":"https:\/\/fruiturisme.info\/fr\/wp-json\/wp\/v2\/posts\/10268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fruiturisme.info\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fruiturisme.info\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fruiturisme.info\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fruiturisme.info\/fr\/wp-json\/wp\/v2\/comments?post=10268"}],"version-history":[{"count":9,"href":"https:\/\/fruiturisme.info\/fr\/wp-json\/wp\/v2\/posts\/10268\/revisions"}],"predecessor-version":[{"id":10282,"href":"https:\/\/fruiturisme.info\/fr\/wp-json\/wp\/v2\/posts\/10268\/revisions\/10282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fruiturisme.info\/fr\/wp-json\/wp\/v2\/media\/10269"}],"wp:attachment":[{"href":"https:\/\/fruiturisme.info\/fr\/wp-json\/wp\/v2\/media?parent=10268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fruiturisme.info\/fr\/wp-json\/wp\/v2\/categories?post=10268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fruiturisme.info\/fr\/wp-json\/wp\/v2\/tags?post=10268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}